{"id":72014,"date":"2023-09-30T16:35:23","date_gmt":"2023-09-30T20:35:23","guid":{"rendered":"https:\/\/pinstripesnation.com\/la-pesadilla-de-162-millones-de-dolares-de-carlos-rodon-deberian-los-aficionados-tacharlo-de-catastrofe-de-los-yankees\/"},"modified":"2023-09-30T16:44:35","modified_gmt":"2023-09-30T20:44:35","slug":"la-pesadilla-de-162-millones-de-dolares-de-carlos-rodon-deberian-los-aficionados-tacharlo-de-catastrofe-de-los-yankees","status":"publish","type":"post","link":"https:\/\/pinstripesnation.com\/es\/la-pesadilla-de-162-millones-de-dolares-de-carlos-rodon-deberian-los-aficionados-tacharlo-de-catastrofe-de-los-yankees\/","title":{"rendered":"La pesadilla de 162 millones de d\u00f3lares de Carlos Rodon: \u00bfDeber\u00edan los aficionados tacharlo de cat\u00e1strofe de los Yankees?"},"content":{"rendered":"\n<p>En lo que s\u00f3lo puede describirse como un final de pesadilla para su primera temporada con los <a href=\"https:\/\/pinstripesnation.com\">Yankees de Nueva<\/a> York, Carlos Rod\u00f3n, el lanzador zurdo que hab\u00eda firmado un contrato de seis a\u00f1os y 162 millones de d\u00f3lares con el equipo en la temporada baja, se enfrent\u00f3 a una <a href=\"https:\/\/pinstripesnation.com\/es\/los-yankees-no-se-recuperan-de-la-temprana-sacudida-de-rodon-y-pierden-12-5-ante-los-royals\/\">salida catastr\u00f3fica contra los Reales de Kansas City<\/a> el viernes. En esta devastadora salida, cedi\u00f3 la friolera de ocho carreras sin lograr ni un solo out. A medida que se desarrollaba la p\u00e9sima actuaci\u00f3n, Rodon permiti\u00f3 que sus frustraciones tomaran el control, cometiendo un notable acto de falta de respeto hacia el entrenador de lanzadores de los Yankees, Matt Blake, durante una visita crucial al mont\u00edculo.<\/p>\n\n<p>La desastrosa exhibici\u00f3n sirvi\u00f3 de marcado contraste con las expectativas que acompa\u00f1aron a la llegada de Carlos Rod\u00f3n al Bronx. Tras una temporada plagada de lesiones que le limitaron a s\u00f3lo 13 titularidades, guard\u00f3 lo peor para el final. Esta actuaci\u00f3n dej\u00f3 perplejos a los aficionados y a la direcci\u00f3n del equipo, que se preguntaban c\u00f3mo el prometedor as que hab\u00edan anticipado pod\u00eda deshacerse de forma tan espectacular.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"827\" src=\"https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190-1200x827.png\" alt=\"\" class=\"wp-image-72009\" srcset=\"https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190-1200x827.png 1200w, https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190-300x207.png 300w, https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190-768x529.png 768w, https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190-120x83.png 120w, https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190-991x683.png 991w, https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-190.png 1280w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<p>El momento cr\u00edtico de la contienda surgi\u00f3 durante una visita al mont\u00edculo del entrenador de lanzadores Matt Blake. Para cuando Blake se acerc\u00f3 a Rodon, el zurdo ya hab\u00eda concedido cuatro carreras, y otros dos bateadores de los Royals hab\u00edan alcanzado la base. Al principio, Rodon pareci\u00f3 entablar conversaci\u00f3n con Blake, presumiblemente en busca de orientaci\u00f3n o tranquilidad. Sin embargo, le invadi\u00f3 una oleada de frustraci\u00f3n que le llev\u00f3 a dar la espalda a Blake e incluso a hacer un gesto al entrenador para que se retirara al banquillo. Ambos mantuvieron una breve conversaci\u00f3n cara a cara antes de que Blake abandonara el mont\u00edculo.<\/p>\n\n<p>Tras esta alarmante exhibici\u00f3n, Carlos Rod\u00f3n, en un momento de autorreflexi\u00f3n, reconoci\u00f3 su atroz comportamiento. Admiti\u00f3 p\u00fablicamente su verg\u00fcenza, reconociendo la gravedad de sus actos. En sus propias palabras, declar\u00f3 que \u00abno estaba en sus cabales\u00bb durante la visita al mont\u00edculo y acept\u00f3 toda la responsabilidad por su conducta. Su disposici\u00f3n a aceptar la culpa demostr\u00f3 un grado de madurez en medio de la confusi\u00f3n, un reconocimiento de que sus acciones estaban lejos de lo que se esperaba de un atleta profesional.<\/p>\n\n<p>Adem\u00e1s, tras la conclusi\u00f3n del partido, Carlos Rodon mantuvo una larga conversaci\u00f3n a puerta cerrada con el entrenador de los Yankees, Aaron Boone, lo que sugiere que el equipo se tom\u00f3 en serio el asunto. Boone, aunque reconoci\u00f3 la dif\u00edcil temporada que Rod\u00f3n hab\u00eda soportado, hizo hincapi\u00e9 en la necesidad de una \u00abmejor presencia en el mont\u00edculo\u00bb por parte del lanzador, insinuando que el incidente fue considerado irrespetuoso por el cuerpo t\u00e9cnico.<\/p>\n\n<p>Matt Blake, que fue el destinatario de las acciones de Rod\u00f3n, expres\u00f3 su punto de vista sobre el asunto. Confirm\u00f3 que a\u00fan no hab\u00eda hablado con Rod\u00f3n sobre el incidente, pero se abstuvo de interpretarlo como un \u00abataque personal\u00bb. No obstante, recalc\u00f3 que ese comportamiento era inaceptable, proclamando: \u00abNo se puede actuar as\u00ed\u00bb, y a\u00f1adi\u00f3: \u00abNo podemos permitir que vuelva a ocurrir\u00bb. La respuesta de Blake subraya la importancia de la profesionalidad y la deportividad en la organizaci\u00f3n de los Yankees.<\/p>\n\n<h2 class=\"wp-block-heading\">Colapso hist\u00f3rico de Carlos Rod\u00f3n: Un rasca cabezas de los Yankees<\/h2>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/pinstripesnation.com\/wp-content\/uploads\/2023\/09\/image-189-1200x800.png\" alt=\"\" class=\"wp-image-72007\"\/><\/figure>\n\n<p>La salida de pesadilla de Carlos Rodon marc\u00f3 la culminaci\u00f3n de una lamentable primera temporada con los Yankees. En 13 salidas, registr\u00f3 un p\u00e9simo ERA de 5,74, muy lejos de las expectativas asociadas a su llegada. Para empeorar las cosas, su hist\u00f3ricamente terrible comienzo contra los Royals le hizo entrar en los libros de r\u00e9cords por todas las razones equivocadas, empatando un r\u00e9cord establecido por s\u00f3lo otros cinco lanzadores desde 1901. Se convirti\u00f3 en el primer lanzador de los Yankees en permitir ocho carreras sin registrar un out en una salida.<\/p>\n\n<p>La frustraci\u00f3n y la decepci\u00f3n que rodearon la actuaci\u00f3n de Carlos Rod\u00f3n en esta fat\u00eddica noche fueron palpables. Fue un final descorazonador para una temporada que promet\u00eda mucho. Ahora, de cara a la temporada baja, Rod\u00f3n carga con el peso de las expectativas y la determinaci\u00f3n de recuperarse de su desastroso primer a\u00f1o a rayas.<\/p>\n\n<p>A medida que los Yankees concluyen su temporada, sin duda tienen muchas preguntas que abordar, incluido el futuro de Carlos Rodon. Queda por ver si podr\u00e1 recuperarse de esta temporada de pesadilla y recuperar la forma que le vali\u00f3 su enorme contrato. Sin embargo, una cosa est\u00e1 clara: los Yankees, sus aficionados y el propio Rod\u00f3n estar\u00e1n muy atentos, esperando una historia de redenci\u00f3n en las pr\u00f3ximas temporadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En lo que s\u00f3lo puede describirse como un final de pesadilla para su primera temporada con los Yankees de Nueva York, Carlos Rod\u00f3n, el lanzador zurdo que hab\u00eda firmado un contrato de seis a\u00f1os y 162 millones de d\u00f3lares con el equipo en la temporada baja, se enfrent\u00f3 a una salida catastr\u00f3fica contra los Reales [&hellip;]<\/p>\n","protected":false},"author":141,"featured_media":72012,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[897],"tags":[960,829],"class_list":["post-72014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-carlos-rodon-es","tag-yankees-de-nueva-york"],"acf":[],"_links":{"self":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/72014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/comments?post=72014"}],"version-history":[{"count":0,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/72014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media\/72012"}],"wp:attachment":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media?parent=72014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/categories?post=72014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/tags?post=72014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}