{"id":245237,"date":"2026-09-02T06:43:48","date_gmt":"2026-09-02T10:43:48","guid":{"rendered":"https:\/\/pinstripesnation.com\/jazz-chisholm-responde-a-las-bromas-de-la-bancada-de-los-yankees-con-su-bate-y-un-gesto-elocuente\/"},"modified":"2026-09-02T06:45:21","modified_gmt":"2026-09-02T10:45:21","slug":"jazz-chisholm-responde-a-las-bromas-de-la-bancada-de-los-yankees-con-su-bate-y-un-gesto-elocuente","status":"publish","type":"post","link":"https:\/\/pinstripesnation.com\/es\/jazz-chisholm-responde-a-las-bromas-de-la-bancada-de-los-yankees-con-su-bate-y-un-gesto-elocuente\/","title":{"rendered":"Jazz Chisholm responde a las cr\u00edticas sobre su actitud en el banquillo de los Yankees con su bate y un gesto elocuente"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">ANAHEIM, California \u2014 El segunda base de los Yankees no necesit\u00f3 un micr\u00f3fono para responder a las preguntas del lunes, que le siguieron hasta la noche del martes.<\/p>\n\n<p class=\"wp-block-paragraph\">Una noche despu\u00e9s de que las c\u00e1maras de televisi\u00f3n captaran a <a href=\"https:\/\/pinstripesnation.com\/es\/quien-es-jazz-chisholm-la-sensacion-nacida-en-bahamas-que-causa-sensacion-con-los-yankees\/\">Jazz Chisholm Jr.<\/a> sonriendo y bromeando con sus compa\u00f1eros de equipo durante una dura derrota ante los \u00c1ngeles Angels, el jugador de campo ofreci\u00f3 una imagen muy diferente.<\/p>\n\n<p class=\"wp-block-paragraph\">Lanz\u00f3 una bola r\u00e1pida a 98,1 mph que super\u00f3 la valla del campo izquierdo en el Angel Stadium, lo que ayud\u00f3 a los Yankees a conseguir una <a href=\"https:\/\/pinstripesnation.com\/es\/la-victoria-de-los-yankees-por-7-3-sobre-los-angels-no-puede-ocultar-la-senal-de-alarma-que-nos-da-gerrit-cole\/\">ventaja inmediata de tres carreras en su victoria por 7-3<\/a>. Despu\u00e9s, durante la celebraci\u00f3n que sigui\u00f3, Chisholm se tap\u00f3 la boca con la mano.<\/p>\n\n<p class=\"wp-block-paragraph\">El gesto ten\u00eda un simbolismo evidente tras la reacci\u00f3n de la noche anterior, aunque Chisholm no lo presentara p\u00fablicamente como una respuesta a sus cr\u00edticos.<\/p>\n\n<p class=\"wp-block-paragraph\">El contraste era dif\u00edcil de pasar por alto.<\/p>\n\n<p class=\"wp-block-paragraph\">Veinticuatro horas antes, los Yankees estaban pasando por un mal trago ante uno de los peores equipos de la Liga Americana. Al final de <a href=\"https:\/\/pinstripesnation.com\/es\/10-1-los-yankees-pierden-por-culpa-de-sus-propios-errores-no-porque-los-angels-fueran-muy-fuertes\/\">la derrota del lunes por 10-1<\/a>, Nueva York hab\u00eda cometido tres errores y encajado 12 hits, mientras que la racha de siete derrotas consecutivas de los Angels lleg\u00f3 a su fin de forma abrupta.<\/p>\n\n<p class=\"wp-block-paragraph\">La actitud de Chisholm durante la goleada se convirti\u00f3 en tema de conversaci\u00f3n tras la derrota. Los Yankees iban perdiendo 7-1 al final de la sexta entrada, y las im\u00e1genes en las que se le ve\u00eda relajado y bromeando en el banquillo suscitaron cr\u00edticas sobre si aquel momento no exig\u00eda una reacci\u00f3n m\u00e1s seria.<\/p>\n\n<figure class=\"wp-block-embed is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The Yankees were seen joking around in the dugout while down 7-1 to the Angels last night. <a href=\"https:\/\/t.co\/kiByV7cH0o\">pic.twitter.com\/kiByV7cH0o<\/a><\/p>&mdash; New York Post Sports (@nypostsports) <a href=\"https:\/\/x.com\/nypostsports\/status\/2094814902804226513?ref_src=twsrc%5Etfw\">September 1, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<p class=\"wp-block-paragraph\">El martes, su respuesta lleg\u00f3 en el bate con dos carreras, un jonr\u00f3n y dos sencillos. Y con una jugada divertida.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Tras las declaraciones de Jazz Chisholm se desata un debate ya conocido<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Las dudas sobre la personalidad de Chisholm no son nada nuevo.<\/p>\n\n<p class=\"wp-block-paragraph\">Su energ\u00eda es una de las razones por las que los Yankees lo han acogido con los brazos abiertos. Pero tambi\u00e9n lo convierte en uno de los jugadores m\u00e1s criticados cuando las cosas van mal.<\/p>\n\n<p class=\"wp-block-paragraph\">A principios de esta temporada, Chisholm llam\u00f3 la atenci\u00f3n por salir al <a href=\"https:\/\/pinstripesnation.com\/es\/el-momento-blow-pop-de-jazz-chisholm-desata-una-tormenta-en-los-yankees-con-boone-en-el-punto-de-mira\/\">campo con una piruleta en la boca<\/a>. El entrenador Aaron Boone se pronunci\u00f3 al respecto, y el episodio se convirti\u00f3 r\u00e1pidamente en un cap\u00edtulo m\u00e1s del debate constante en torno al estilo de Chisholm.<\/p>\n\n<p class=\"wp-block-paragraph\">Sus compa\u00f1eros de equipo suelen describir esa personalidad de otra manera.<\/p>\n\n<p class=\"wp-block-paragraph\">Chisholm dijo el mes pasado que tomarse el b\u00e9isbol con calma le ha ayudado a superar los momentos dif\u00edciles. Le dio las gracias al vestuario de los Yankees por ayudarle a superar la frustraci\u00f3n y a concentrarse en otras formas de influir en el partido.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abA veces es frustrante, pero tengo unos compa\u00f1eros de equipo tan geniales en el vestuario que simplemente mantengo la cabeza despierta\u00bb, dijo Chisholm en agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSalgo a defender lo mejor que puedo y, cuando consigo llegar a base, corro por ellas lo mejor que puedo. Eso me recuerda el talento que tengo y todo lo que he conseguido antes\u00bb.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Ese contexto hace que la escena del lunes sea m\u00e1s complicada de lo que parece en una foto o en un breve v\u00eddeo del banquillo.<\/p>\n\n<p class=\"wp-block-paragraph\">Chisholm ha defendido en repetidas ocasiones que jugar sin complejos es parte de su forma de jugar bien. Los Yankees tambi\u00e9n se han beneficiado de esa misma agresividad y personalidad que, a veces, lo convierten en un blanco f\u00e1cil cuando el equipo pasa por un mal momento.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Chisholm convierte las cr\u00edticas en una respuesta inmediata de los Yankees<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Los Yankees no tardaron mucho en cambiar el ambiente que se hab\u00eda creado en el primer partido de la serie.<\/p>\n\n<p class=\"wp-block-paragraph\">Con dos outs en la primera entrada, el novato <a href=\"https:\/\/pinstripesnation.com\/es\/quien-es-spencer-jones-el-recluta-de-los-yankees-con-cualidades-similares-a-las-de-aaron-judge\/\">Spencer Jones<\/a> mand\u00f3 un lanzamiento de Grayson Rodr\u00edguez por encima de la valla del centro-derecha para un jonr\u00f3n de dos carreras. Chisholm le sigui\u00f3 enseguida.<\/p>\n\n<p class=\"wp-block-paragraph\">Rodr\u00edguez le lanz\u00f3 una bola r\u00e1pida de cuatro costuras a 98,1 mph con un conteo de 2-2. Chisholm la sigui\u00f3 bien y la mand\u00f3 al otro lado del campo.<\/p>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan <a href=\"https:\/\/baseballsavant.mlb.com\/savant-player\/jazz-chisholm-jr-665862?stats=statcast-r-hitting-mlb\" target=\"_blank\" rel=\"noopener\">MLB Statcast<\/a>, la bola vol\u00f3 340 pies y super\u00f3 por muy poco la valla del campo izquierdo, lo que supuso el decimonoveno jonr\u00f3n de Chisholm esta temporada. La bola sali\u00f3 de su bate a 95,4 mph con un \u00e1ngulo de lanzamiento de 25 grados.<\/p>\n\n<p class=\"wp-block-paragraph\">Y as\u00ed, sin m\u00e1s, los Yankees se pusieron 3-0 por delante.<\/p>\n\n<p class=\"wp-block-paragraph\">El jonr\u00f3n fue solo el principio. Chisholm acab\u00f3 con 3 de 5, dos carreras anotadas y una carrera impulsada, lo que elev\u00f3 su promedio de bateo a 0,232. Fue su primer partido con tres hits desde la aplastante victoria de los Yankees sobre Boston el 30 de agosto.<\/p>\n\n<p class=\"wp-block-paragraph\">Lo que importaba era su rendimiento, m\u00e1s que cualquier interpretaci\u00f3n de lo que pas\u00f3 despu\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Aun as\u00ed, la imagen fue llamativa. Tras dar la vuelta a las bases, Chisholm se tap\u00f3 la boca durante la celebraci\u00f3n. Al producirse menos de un d\u00eda despu\u00e9s de que su actitud en el banquillo hubiera suscitado cr\u00edticas, el gesto parec\u00eda el de un jugador que dejaba claro su mensaje sin decir apenas nada.<\/p>\n\n<p class=\"wp-block-paragraph\">A\u00fan no se sabe con certeza si esa interpretaci\u00f3n era lo que Chisholm quer\u00eda decir.<\/p>\n\n<figure class=\"wp-block-embed is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Late-Night Jazz Solo. \ud83c\udfb7\ud83d\udd25<a href=\"https:\/\/x.com\/hashtag\/Yankees?src=hash&amp;ref_src=twsrc%5Etfw\">#Yankees<\/a> <a href=\"https:\/\/x.com\/hashtag\/RepBX?src=hash&amp;ref_src=twsrc%5Etfw\">#RepBX<\/a> <a href=\"https:\/\/x.com\/hashtag\/MLB?src=hash&amp;ref_src=twsrc%5Etfw\">#MLB<\/a> <a href=\"https:\/\/t.co\/oqS1Dts1Al\">pic.twitter.com\/oqS1Dts1Al<\/a><\/p>&mdash; Pinstripes Nation (@pinstripesnat) <a href=\"https:\/\/x.com\/pinstripesnat\/status\/2094980204716593423?ref_src=twsrc%5Etfw\">September 2, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\"><strong>Los Yankees consiguen al Chisholm que necesitan<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">El martes se present\u00f3 un argumento m\u00e1s claro.<\/p>\n\n<p class=\"wp-block-paragraph\">Chisholm bate\u00f3.<\/p>\n\n<p class=\"wp-block-paragraph\">Los Yankees ganaron.<\/p>\n\n<p class=\"wp-block-paragraph\">Y su actuaci\u00f3n lleg\u00f3 justo cuando Nueva York necesitaba evitar que el desastroso inicio de la serie se convirtiera en algo a\u00fan m\u00e1s perjudicial.<\/p>\n\n<p class=\"wp-block-paragraph\">Los \u00c1ngeles recort\u00f3 la ventaja inicial de 4-0 de los Yankees hasta el 4-3 en la sexta entrada, pero el bullpen de Nueva York evit\u00f3 que el partido diera un giro. A continuaci\u00f3n, los Yankees anotaron dos veces en la octava y una en la novena para sentenciar el partido.<\/p>\n\n<p class=\"wp-block-paragraph\">Jones termin\u00f3 con 2 de 3, dos bases por bolas, tres carreras impulsadas, dos carreras anotadas y una base robada. Cody Bellinger sum\u00f3 tres hits. Gerrit Cole cedi\u00f3 tres carreras y ocho hits en 5 1\/3 entradas y se llev\u00f3 la victoria.<\/p>\n\n<p class=\"wp-block-paragraph\">Con este resultado, los <a href=\"https:\/\/pinstripesnation.com\/es\/\">Yankees quedan con un balance de <\/a>79-60. Siguen a 4,5 partidos de Tampa Bay en la Divisi\u00f3n Este de la Liga Americana y mantienen una ventaja de cuatro partidos sobre Boston en la lucha por el primer puesto de comod\u00edn de la Liga Americana.<\/p>\n\n<p class=\"wp-block-paragraph\">Para Chisholm, hab\u00eda otra faceta.<\/p>\n\n<p class=\"wp-block-paragraph\">Lleg\u00f3 a la serie ya en medio de <a href=\"https:\/\/pinstripesnation.com\/es\/un-comentarista-de-los-red-sox-incita-a-la-violencia-contra-wells-y-jazz-tras-la-derrota-ante-los-yankees\/\">una pol\u00e9mica despu\u00e9s de que el comentarista de los Red Sox, Will <\/a>Flemming, lo criticara por robar dos bases cuando los Yankees ganaban a Boston por 7-1 el domingo. Boone revel\u00f3 m\u00e1s tarde que \u00e9l mismo le hab\u00eda dicho a Chisholm que corriera. Flemming se disculp\u00f3 despu\u00e9s por unos comentarios que fueron m\u00e1s all\u00e1 de criticar los robos de base.<\/p>\n\n<p class=\"wp-block-paragraph\">As\u00ed que Chisholm pas\u00f3 de que le criticaran por jugar de forma demasiado agresiva en un partido muy desigual a que le criticaran por parecer demasiado relajado en otro, todo ello en unos dos d\u00edas.<\/p>\n\n<p class=\"wp-block-paragraph\">El martes le dio la respuesta m\u00e1s sencilla que puede tener un jugador en medio de ese tipo de debate.<\/p>\n\n<p class=\"wp-block-paragraph\">Un jonr\u00f3n. Tres hits. Una victoria de los Yankees.<\/p>\n\n<p class=\"wp-block-paragraph\">Y luego, al menos durante un momento que llam\u00f3 la atenci\u00f3n, se tap\u00f3 la boca.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 te parece? Deja tu comentario m\u00e1s abajo.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANAHEIM, California \u2014 El segunda base de los Yankees no necesit\u00f3 un micr\u00f3fono para responder a las preguntas del lunes, que le siguieron hasta la noche del martes. Una noche despu\u00e9s de que las c\u00e1maras de televisi\u00f3n captaran a Jazz Chisholm Jr. sonriendo y bromeando con sus compa\u00f1eros de equipo durante una dura derrota ante [&hellip;]<\/p>\n","protected":false},"author":43,"featured_media":245235,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[2945,897,3583],"tags":[9931,9932,2942,8409,1585,3539,1100,829],"class_list":["post-245237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jazz-chisholm-jr-es","category-noticias","category-spencer-jones-es","tag-angel-stadium","tag-critica-de-jazz-chisholm","tag-jazz-chisholm-jr-es-2","tag-jonron-de-jazz-chisholm","tag-mlb-es","tag-noticias-de-los-yankees","tag-yankees-contra-angels","tag-yankees-de-nueva-york"],"acf":[],"_links":{"self":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/245237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/comments?post=245237"}],"version-history":[{"count":2,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/245237\/revisions"}],"predecessor-version":[{"id":245240,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/245237\/revisions\/245240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media\/245235"}],"wp:attachment":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media?parent=245237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/categories?post=245237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/tags?post=245237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}