{"id":245226,"date":"2026-09-02T06:22:17","date_gmt":"2026-09-02T10:22:17","guid":{"rendered":"https:\/\/pinstripesnation.com\/la-victoria-de-los-yankees-por-7-3-sobre-los-angels-no-puede-ocultar-la-senal-de-alarma-que-nos-da-gerrit-cole\/"},"modified":"2026-09-02T06:25:27","modified_gmt":"2026-09-02T10:25:27","slug":"la-victoria-de-los-yankees-por-7-3-sobre-los-angels-no-puede-ocultar-la-senal-de-alarma-que-nos-da-gerrit-cole","status":"publish","type":"post","link":"https:\/\/pinstripesnation.com\/es\/la-victoria-de-los-yankees-por-7-3-sobre-los-angels-no-puede-ocultar-la-senal-de-alarma-que-nos-da-gerrit-cole\/","title":{"rendered":"La victoria de los Yankees por 7-3 sobre los Angels no puede ocultar la se\u00f1al de alarma que nos da Gerrit Cole"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">ANAHEIM, California \u2014 El primer lanzamiento ni siquiera hab\u00eda salido de la mano de Gerrit Cole, y los Yankees de Nueva York ya iban ganando por tres.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/pinstripesnation.com\/es\/quien-es-j-d-davis-el-sustituto-de-stanton-en-los-yankees\/\">Spencer Jones<\/a> conect\u00f3 un jonr\u00f3n de dos carreras que se fue a las gradas. Jazz Chisholm Jr. le sigui\u00f3 con un batazo al campo contrario que se col\u00f3 en la esquina del campo izquierdo. Dos jonrones seguidos, antes de que ning\u00fan jugador de los Angels llegara al bate en la parte baja de la entrada.<\/p>\n\n<p class=\"wp-block-paragraph\">Fue el tipo de comienzo que los Yankees llevaban todo el verano deseando. Llevaban un mes sin dar la talla con los bates en las primeras entradas. El martes por la noche, se rompi\u00f3 el hielo enseguida.<\/p>\n\n<p class=\"wp-block-paragraph\">As\u00ed que, durante cinco entradas, parec\u00eda que iba a ser la noche m\u00e1s impecable que los Yankees hab\u00edan tenido en mucho tiempo. Cole jug\u00f3 en el estadio donde creci\u00f3. Mantuvo la ventaja. Sus compa\u00f1eros encadenaron un hit tras otro. <a href=\"https:\/\/pinstripesnation.com\/es\/10-1-los-yankees-pierden-por-culpa-de-sus-propios-errores-no-porque-los-angels-fueran-muy-fuertes\/\">La derrota por 10-1 de la noche anterior <\/a>parec\u00eda ya un recuerdo lejano.<\/p>\n\n<p class=\"wp-block-paragraph\">Entonces lleg\u00f3 la sexta entrada. Y, por segunda salida consecutiva, ah\u00ed fue donde la noche de Cole dio un giro.<\/p>\n\n<p class=\"wp-block-paragraph\">Los <a href=\"https:\/\/www.espn.com\/mlb\/boxscore\/_\/gameId\/401816770\" target=\"_blank\" rel=\"noopener\">Yankees acabaron ganando, 7-3<\/a>, a los reci\u00e9n vendidos \u00c1ngeles de Los \u00c1ngeles en el Angel Stadium. Nueva York sum\u00f3 14 hits. Jones lleg\u00f3 a base cuatro veces e impuls\u00f3 tres carreras. Chisholm sum\u00f3 tres hits. La alineaci\u00f3n lo dio todo.<\/p>\n\n<p class=\"wp-block-paragraph\">Pero lo que el marcador apenas deja entrever no es la ofensiva. Es el patr\u00f3n que se est\u00e1 formando en torno al co-as de los Yankees justo en el peor momento del a\u00f1o.<\/p>\n\n<figure class=\"wp-block-embed is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">ANOTHER RBI FOR SPENCER JONES! \ud83d\udd25\ud83d\udcaa He drops a single into left field to bring another run home!<a href=\"https:\/\/x.com\/hashtag\/Yankees?src=hash&amp;ref_src=twsrc%5Etfw\">#Yankees<\/a> <a href=\"https:\/\/x.com\/hashtag\/RepBX?src=hash&amp;ref_src=twsrc%5Etfw\">#RepBX<\/a> <a href=\"https:\/\/x.com\/hashtag\/MLB?src=hash&amp;ref_src=twsrc%5Etfw\">#MLB<\/a> <a href=\"https:\/\/t.co\/BELDrEaaFt\">pic.twitter.com\/BELDrEaaFt<\/a><\/p>&mdash; Pinstripes Nation (@pinstripesnat) <a href=\"https:\/\/x.com\/pinstripesnat\/status\/2095004867765154095?ref_src=twsrc%5Etfw\">September 2, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\"><strong>Un problema recurrente en la sexta entrada para Cole<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cole (8-7) encaj\u00f3 tres carreras y ocho hits en 5\u2153 entradas. Ponch\u00f3 a cinco y concedi\u00f3 una base por bolas. Durante casi toda la noche, pareci\u00f3 el lanzador en el que los Yankees confiar\u00e1n en octubre.<\/p>\n\n<p class=\"wp-block-paragraph\">El problema lleg\u00f3 en una sola entrada. Los \u00c1ngeles perd\u00eda por 4-1 cuando Wade Meckler abri\u00f3 la sexta con un sencillo. Moises Ballesteros conect\u00f3 otro sencillo justo despu\u00e9s. Luego, Christian Moore bate\u00f3 un triple de dos carreras hacia la derecha que Jones, a pesar de lanzarse en picado, no pudo alcanzar. La ventaja se redujo a 4-3, y la carrera del empate estaba en tercera.<\/p>\n\n<p class=\"wp-block-paragraph\">Sacaron a Cole. Su noche se acab\u00f3 con ese sencillo.<\/p>\n\n<p class=\"wp-block-paragraph\">Por s\u00ed solo, eso se ver\u00eda como un tropiezo habitual. Lo que hace que merezca la pena prestarle atenci\u00f3n es el contexto. Cole tambi\u00e9n se meti\u00f3 en un buen l\u00edo en la sexta entrada de su anterior salida, contra Houston. Dos salidas seguidas, la misma entrada, el mismo colapso. Para un lanzador en su primera temporada completa tras recuperarse de una operaci\u00f3n de Tommy John, un baj\u00f3n repetido en las \u00faltimas entradas es el tipo de detalle que un equipo aspirante al t\u00edtulo tiene muy en cuenta.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/pinstripesnation.com\/es\/gerrit-cole-envia-a-los-yankees-un-mensaje-claro-para-que-aceleren-su-regreso\/\">Cole debut\u00f3 en la temporada 2026<\/a> a finales de mayo, tras la operaci\u00f3n de codo. Los Yankees han vigilado de cerca su carga de trabajo durante todo el a\u00f1o. Una tendencia que se concentra en la sexta entrada no supone una crisis en septiembre. Es un dato que el cuerpo t\u00e9cnico no puede pasar por alto en una rotaci\u00f3n que apunta a los playoffs.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Un relevista discreto respondi\u00f3 en el momento m\u00e1s importante de los Yankees<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cuando Cole se retir\u00f3, el partido se jugaba en un solo turno al bate. La carrera del empate estaba a 90 pies de distancia con un out. Ese fue el momento m\u00e1s peligroso de la noche para los Yankees, y le toc\u00f3 a un relevista del que la mayor\u00eda de los aficionados casi nunca hablan.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/pinstripesnation.com\/es\/?p=231251\">Brent Headrick<\/a> entr\u00f3 al campo y elimin\u00f3 por strikeout al bateador suplente Jos\u00e9 Siri. A continuaci\u00f3n, consigui\u00f3 que Oswald Peraza bateara una bola alta. La amenaza se esfum\u00f3. La ventaja se mantuvo. Headrick ya ha dejado en base a 38 de los 42 corredores que ha heredado esta temporada, una cifra que, sin hacer mucho ruido, se sit\u00faa entre las mejores del equipo.<\/p>\n\n<p class=\"wp-block-paragraph\">El entrenador Aaron Boone atribuy\u00f3 la victoria al esfuerzo de toda la plantilla, en lugar de a la actuaci\u00f3n de dos jugadores en particular, y destac\u00f3 las numerosas peque\u00f1as contribuciones que, sumadas, dieron el resultado.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abEs que esta noche todo el mundo est\u00e1 aportando su granito de arena\u00bb, dijo Boone.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Jones, que se ha colado en la conversaci\u00f3n sobre octubre, se centr\u00f3 en c\u00f3mo esa ventaja inicial marc\u00f3 todo lo que vino despu\u00e9s.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abMarcar en la primera entrada de cualquier partido, sobre todo en uno en el que hay que remontar tras una derrota, es muy importante\u00bb, dijo Jones. \u00abEl simple hecho de poder jugar con ventaja durante la mayor parte del partido y poner en marcha el ataque desde el principio es muy importante para el equipo\u00bb.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">Chisholm, que conect\u00f3 un jonr\u00f3n justo despu\u00e9s de Jones, dej\u00f3 claro c\u00f3mo ve el equipo el gran momento del joven jardinero.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab[Jones] es un gran jugador, un chaval estupendo\u00bb, dijo Chisholm. \u00abLlevamos a\u00f1os oyendo hablar de \u00e9l y ahora tiene la oportunidad de demostrarlo. Me alegro mucho por \u00e9l\u00bb.<\/p>\n<\/blockquote>\n\n<figure class=\"wp-block-embed is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">ANOTHER RBI FOR SPENCER JONES! \ud83d\udd25\ud83d\udcaa He drops a single into left field to bring another run home!<a href=\"https:\/\/x.com\/hashtag\/Yankees?src=hash&amp;ref_src=twsrc%5Etfw\">#Yankees<\/a> <a href=\"https:\/\/x.com\/hashtag\/RepBX?src=hash&amp;ref_src=twsrc%5Etfw\">#RepBX<\/a> <a href=\"https:\/\/x.com\/hashtag\/MLB?src=hash&amp;ref_src=twsrc%5Etfw\">#MLB<\/a> <a href=\"https:\/\/t.co\/BELDrEaaFt\">pic.twitter.com\/BELDrEaaFt<\/a><\/p>&mdash; Pinstripes Nation (@pinstripesnat) <a href=\"https:\/\/x.com\/pinstripesnat\/status\/2095004867765154095?ref_src=twsrc%5Etfw\">September 2, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\"><strong>La capacidad de Headrick para salir airoso de situaciones con una carrera de diferencia es un tesoro para los Yankees<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En los dos \u00faltimos partidos de los Yankees, todos los corredores que Cole dej\u00f3 en manos del bullpen en la sexta entrada se quedaron en las bases. Entre el lunes y el martes, el cuerpo de relevos de Nueva York no permiti\u00f3 que ni un solo corredor heredado de Cole anotara, a pesar de que los Angels llevaron la carrera del empate a posici\u00f3n de anotaci\u00f3n dos veces solo en este partido.<\/p>\n\n<p class=\"wp-block-paragraph\">Ese detalle cambia la perspectiva sobre lo que pasa en la sexta entrada. Los Yankees a\u00fan no est\u00e1n pagando las consecuencias de los bajones de Cole al final de los partidos porque el bullpen sigue cerrando bien la puerta tras \u00e9l. El registro de Headrick, con 38 de 42 en corredores heredados, es lo que lo hace posible. Tambi\u00e9n es un margen muy ajustado en el que confiar durante todo octubre, y precisamente por eso es importante fijarse en esta tendencia ahora y no m\u00e1s adelante.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>La victoria ha cambiado las perspectivas de los Yankees en la lucha por el comod\u00edn<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">El resultado tuvo repercusiones m\u00e1s all\u00e1 de un solo partido. Nueva York mejor\u00f3 su balance a 79-60 y se mantuvo a 4\u00bd partidos del l\u00edder, Tampa Bay, en la Divisi\u00f3n Este de la Liga Americana, a falta de 23 partidos. Los Rays tambi\u00e9n ganaron, as\u00ed que los Yankees no recortaron distancias en la divisi\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">La recompensa lleg\u00f3 desde Boston. Los Red Sox perdieron, lo que hizo que los <a href=\"https:\/\/pinstripesnation.com\/es\/\">Yankees se alejaran cuatro <\/a>partidos de ellos en la lucha por el primer puesto de comod\u00edn de la Liga Americana. En una re\u00f1ida carrera por los playoffs, ese colch\u00f3n es justo el tipo de ventaja que se espera conseguir en una noche de septiembre.<\/p>\n\n<p class=\"wp-block-paragraph\">La ofensiva hizo su parte para apoyar a Cole. Jones conect\u00f3 un jonr\u00f3n por segunda noche seguida y lleva un promedio de bateo de .348 con un OPS de 1,044 en sus \u00faltimos 15 partidos. Cody Bellinger sum\u00f3 tres de los 14 hits de los Yankees. Trent Grisham, sumido en una mala racha de 2 de 42, fall\u00f3 dos intentos de toque antes de conectar un sencillo impulsor en la octava entrada. Paul Goldschmidt a\u00f1adi\u00f3 un fly de sacrificio.<\/p>\n\n<p class=\"wp-block-paragraph\">Boone tambi\u00e9n dio la oportunidad al reci\u00e9n llegado John Schreiber, que hab\u00eda sido reclamado tras pasar por la lista de descartes de Kansas City. Esas carreras de seguridad en los \u00faltimos compases permitieron al entrenador dar descanso al cerrador David Bednar y <a href=\"https:\/\/pinstripesnation.com\/es\/la-arriesgada-apuesta-de-los-yankees-por-el-lanzador-de-brazo-lateral-john-schreiber-el-verdugo-de-los-diestros-frente-a-las-senales-de-alarma\/\">dejar la novena entrada en manos de Schreiber<\/a>. Este retir\u00f3 a los tres bateadores seguidos en su debut con los Yankees. Mike Trout, por su parte, se fue de 0 de 4 con dos strikeouts, rompiendo as\u00ed una racha de 13 partidos consecutivos bateando contra Nueva York.<\/p>\n\n<p class=\"wp-block-paragraph\">Grayson Rodr\u00edguez (4-6) se llev\u00f3 la derrota para los Angels, que han perdido nueve de los \u00faltimos once partidos y jugaron su primer partido desde que Kroenke Sports &amp; Entertainment acord\u00f3 comprar una participaci\u00f3n mayoritaria en el club a Arte Moreno.<\/p>\n\n<p class=\"wp-block-paragraph\">Los Yankees sacar\u00e1n a Cam Schlittler (12-6, 2,09 ERA) al mont\u00edculo el mi\u00e9rcoles por la noche contra el zurdo de los Angels, Reid Detmers (4-8, 3,54), en el \u00faltimo partido de la serie. La pr\u00f3xima salida de Cole, y si la sexta entrada vuelve a ser un problema, tendr\u00e1 que esperar a otra noche.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 te parece? Deja tu comentario abajo.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANAHEIM, California \u2014 El primer lanzamiento ni siquiera hab\u00eda salido de la mano de Gerrit Cole, y los Yankees de Nueva York ya iban ganando por tres. Spencer Jones conect\u00f3 un jonr\u00f3n de dos carreras que se fue a las gradas. Jazz Chisholm Jr. le sigui\u00f3 con un batazo al campo contrario que se col\u00f3 [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":245224,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[897,7959,2246,2945,895,3583],"tags":[932,3348,962,806,2919,9926,1585,822,1958,1100,829],"class_list":["post-245226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-brent-headrick","category-gerrit-cole-es","category-jazz-chisholm-jr-es","category-resumen-posterior-al-partido","category-spencer-jones-es","tag-aaron-boone-es","tag-brent-headrick-es","tag-bullpen-de-los-yankees","tag-gerrit-cole-es","tag-jazz-chisholm-jr-es","tag-john-schreiber","tag-mlb-es","tag-spencer-jones-es","tag-trent-grisham-es","tag-yankees-contra-angels","tag-yankees-de-nueva-york"],"acf":[],"_links":{"self":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/245226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/comments?post=245226"}],"version-history":[{"count":1,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/245226\/revisions"}],"predecessor-version":[{"id":245227,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/245226\/revisions\/245227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media\/245224"}],"wp:attachment":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media?parent=245226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/categories?post=245226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/tags?post=245226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}