{"id":241908,"date":"2026-07-15T10:29:27","date_gmt":"2026-07-15T14:29:27","guid":{"rendered":"https:\/\/pinstripesnation.com\/los-yankees-se-arriesgan-a-perder-a-drew-gonzalez-su-eleccion-de-sexta-ronda-del-draft\/"},"modified":"2026-07-15T10:30:31","modified_gmt":"2026-07-15T14:30:31","slug":"los-yankees-se-arriesgan-a-perder-a-drew-gonzalez-su-eleccion-de-sexta-ronda-del-draft","status":"publish","type":"post","link":"https:\/\/pinstripesnation.com\/es\/los-yankees-se-arriesgan-a-perder-a-drew-gonzalez-su-eleccion-de-sexta-ronda-del-draft\/","title":{"rendered":"Los Yankees se arriesgan a perder a Drew Gonz\u00e1lez, su elecci\u00f3n de sexta ronda del draft"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EL PASO, Texas \u2014 Los <a href=\"https:\/\/pinstripesnation.com\/es\/la-promocion-de-los-yankees-en-el-draft-de-2026-todos-los-seleccionados-en-las-20-rondas-y-dos-agentes-libres-no-seleccionados\/\">Yankees llegaron al draft de 2026<\/a> con poco dinero y poca influencia. Una multa por el impuesto de lujo les hizo bajar 10 puestos en su primera selecci\u00f3n, lo que redujo su fondo de bonificaciones a uno de los m\u00e1s peque\u00f1os del b\u00e9isbol. <\/p>\n\n<p class=\"wp-block-paragraph\">Esas cifras determinan todas las decisiones que toma un club a partir de la cuarta ronda. Los estudiantes de \u00faltimo curso de la universidad que no piden mucho dinero firman r\u00e1pido. Los jugadores de instituto que tienen compromisos firmes con universidades no lo hacen, y acaban costando m\u00e1s de lo que sugiere su posici\u00f3n en el draft.  <\/p>\n\n<p class=\"wp-block-paragraph\">Los Yankees se arriesgaron de todos modos. En la sexta ronda, eligieron a un jugador de campo de instituto en lugar de a un bateador universitario que fuera una apuesta segura, apostando por poder sacarlo de un programa de la Big 12 que ya lo hab\u00eda fichado en febrero. <\/p>\n\n<p class=\"wp-block-paragraph\">Tres d\u00edas despu\u00e9s de que se cerrara el draft, esa apuesta sigue sin resolverse. El jugador no ha firmado y, seg\u00fan \u00e9l mismo dice, a\u00fan no se ha decidido. El plazo se extiende hasta el 27 de julio.  <\/p>\n\n<h2 class=\"wp-block-heading\">La elecci\u00f3n que tiene una condici\u00f3n<\/h2>\n\n<p class=\"wp-block-paragraph\">El jugador es Andrew Gonz\u00e1lez, un jugador de campo de 18 a\u00f1os procedente del instituto Americas High School de El Paso, al que a menudo llaman Drew. Los Yankees lo seleccionaron en el puesto n.\u00ba 189 del draft, el primer bateador de instituto de su promoci\u00f3n y su elecci\u00f3n de sexta ronda. <\/p>\n\n<p class=\"wp-block-paragraph\">Sus m\u00e9ritos son de verdad. Gonz\u00e1lez bate\u00f3 13 jonrones, sum\u00f3 54 carreras impulsadas y consigui\u00f3 46 bases por bolas en su \u00faltimo a\u00f1o de instituto, lo que le vali\u00f3 ser incluido en el primer equipo estatal de la Asociaci\u00f3n de Entrenadores de B\u00e9isbol de Institutos de Texas en la categor\u00eda 5A. El El Paso Times lo nombr\u00f3 jugador del a\u00f1o de la ciudad.  <\/p>\n\n<p class=\"wp-block-paragraph\">Llev\u00f3 a los Trailblazers a un balance de 27-10-1 y a llegar hasta la cuarta ronda de los playoffs de la Divisi\u00f3n I de la Clase 5A, donde cayeron ante el que a la postre ser\u00eda el campe\u00f3n, Aledo. Mide 6 pies y 1 pulgada, pesa 195 libras y batea con la izquierda. <\/p>\n\n<p class=\"wp-block-paragraph\">El problema surgi\u00f3 meses antes del draft. Gonz\u00e1lez firm\u00f3 con Texas Tech en febrero, despu\u00e9s de retirar su compromiso con New Mexico State el pasado noviembre. Fue el primer fichaje de los Red Raiders seleccionado en este draft.  <\/p>\n\n<p class=\"wp-block-paragraph\">Los ojeadores ven tanto el atractivo como el riesgo en el mismo perfil. Jim Callis dijo en la retransmisi\u00f3n de MLB Network que Gonz\u00e1lez tiene un potencial de potencia real, pero se pregunt\u00f3 si se mantendr\u00eda en tercera base, ya que la primera base o los jardines son opciones plausibles. No aparec\u00eda en el ranking de los 500 mejores de Baseball America.  <\/p>\n\n<h2 class=\"wp-block-heading\">Dos caminos y una fecha l\u00edmite<\/h2>\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n que tiene ante s\u00ed Gonz\u00e1lez es binaria y definitiva. Si firma con los Yankees, empieza su carrera profesional y pierde su derecho a jugar en la NCAA. Si cumple su compromiso con Texas Tech, se va a Lubbock, donde se formar\u00eda durante tres a\u00f1os y volver\u00eda a ser elegible para el draft tras su temporada de tercer a\u00f1o.  <\/p>\n\n<p class=\"wp-block-paragraph\">Le dijo <a href=\"https:\/\/www.ktsm.com\/sports\/local-sports\/americas-high-school-graduate-drew-gonzalez-drafted-by-new-york-yankees-faces-decision-on-baseball-future\/\" target=\"_blank\" rel=\"noopener\">a KTSM<\/a>, la cadena afiliada a la NBC en El Paso, que a\u00fan no hab\u00eda tomado ninguna decisi\u00f3n. Esa era la situaci\u00f3n en el momento del reportaje de la cadena, y desde entonces no se ha anunciado ning\u00fan fichaje. <\/p>\n\n<p class=\"wp-block-paragraph\">El dinero es la clave. El valor asignado a la elecci\u00f3n n.\u00ba 189 es de 341 800 d\u00f3lares, seg\u00fan MLB Pipeline. Esa cifra marca el punto de partida, pero los Yankees pueden superarla reasignando fondos del fondo com\u00fan de las elecciones que firmen por debajo del valor asignado.  <\/p>\n\n<p class=\"wp-block-paragraph\">Su capacidad para hacerlo es limitada. La penalizaci\u00f3n de 10 selecciones por superar el segundo umbral del impuesto de lujo dej\u00f3 a los Yankees casi a la cola de la liga en cuanto a fondos del fondo de bonificaciones, junto con los Dodgers, los Mets, los Blue Jays y los Phillies. Cada d\u00f3lar que se gasta en la indemnizaci\u00f3n a Gonz\u00e1lez es un d\u00f3lar que no se puede usar en otra cosa.  <\/p>\n\n<h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 los Yankees usaron la elecci\u00f3n de todos modos?<\/h2>\n\n<p class=\"wp-block-paragraph\">Los departamentos de ojeadores no gastan una selecci\u00f3n de las 10 primeras rondas en un jugador que esperan perder. La propia selecci\u00f3n es la se\u00f1al, y los ojeadores que segu\u00edan el tablero de los Yankees lo interpretaron as\u00ed. <\/p>\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n necesitaba bateadores. A\u00f1os de traspasos hab\u00edan mermado las filas de los jugadores de campo, y Gonz\u00e1lez fue el primer bateador de instituto en el que se fijaron, en una promoci\u00f3n que se caracterizaba sobre todo por sus lanzadores. Perfect Game lo situ\u00f3 entre los mejores terceros bases de la promoci\u00f3n de instituto de 2026.  <\/p>\n\n<p class=\"wp-block-paragraph\">Que se adapte al estadio es parte del c\u00e1lculo. Un bateador zurdo con potencia en desarrollo hacia el lado interior es un perfil que los Yankees ya han buscado antes, por razones obvias relacionadas con la corta valla del campo derecho del Yankee Stadium. <\/p>\n\n<p class=\"wp-block-paragraph\">Las noticias locales ya se han inclinado hacia un resultado concreto. KVIA, de El Paso, ha informado de que Gonz\u00e1lez parece dispuesto ahora a empezar su carrera profesional en la organizaci\u00f3n de los Yankees, y presenta el draft como la consecuci\u00f3n de un objetivo que llevaba tiempo persiguiendo. Esa valoraci\u00f3n contrasta con su propia declaraci\u00f3n, seg\u00fan la cual la decisi\u00f3n sigue en el aire.  <\/p>\n\n<h2 class=\"wp-block-heading\">En qu\u00e9 punto va el fichaje<\/h2>\n\n<p class=\"wp-block-paragraph\">No hay nada oficial. Gonz\u00e1lez no figura entre los jugadores seleccionados por los Yankees que han llegado a un acuerdo, un grupo en el que se incluye al lanzador zurdo de primera ronda Hunter Dietz, que cerr\u00f3 el trato unas 50 horas despu\u00e9s de ser seleccionado. <\/p>\n\n<p class=\"wp-block-paragraph\">Gonz\u00e1lez no es la \u00fanica apuesta de instituto de esta promoci\u00f3n que se enfrenta a esta ecuaci\u00f3n. El jardinero Lee Garris, elegido en la 13.\u00aa ronda procedente de un instituto de Virginia, y el campocorto William Cutshall, elegido en la 15.\u00aa ronda y comprometido con Ole Miss, tambi\u00e9n tienen sus propios compromisos. Los Yankees seleccionaron a 20 jugadores y ficharon a dos agentes libres que no hab\u00edan sido seleccionados.  <\/p>\n\n<p class=\"wp-block-paragraph\">La fecha l\u00edmite se encarga del resto. Si Gonz\u00e1lez firma antes del 27 de julio, los <a href=\"https:\/\/pinstripesnation.com\/es\/\">Yankees se hacen con <\/a>un bateador zurdo con mucho potencial y un amplio margen de desarrollo. Si no lo hace, la elecci\u00f3n de sexta ronda no reporta nada, y los Red Raiders se quedan con un jugador de campo interior del primer equipo estatal que se pas\u00f3 el verano sopesando entre un contrato profesional y el vestuario de la universidad.  <\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 le parece? Deje su comentario a continuaci\u00f3n. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL PASO, Texas \u2014 Los Yankees llegaron al draft de 2026 con poco dinero y poca influencia. Una multa por el impuesto de lujo les hizo bajar 10 puestos en su primera selecci\u00f3n, lo que redujo su fondo de bonificaciones a uno de los m\u00e1s peque\u00f1os del b\u00e9isbol. Esas cifras determinan todas las decisiones que [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":241906,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[897,904],"tags":[9385,9313,7029,9384,9382,9383,3642,9386,1099,7169,9387,829],"class_list":["post-241908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-perspectivas","tag-andrew-gonzalez","tag-draft-de-la-mlb-de-2026","tag-draft-de-los-yankees","tag-drew-gonzalez","tag-el-paso","tag-fecha-limite-de-inscripcion","tag-fondo-de-bonificaciones","tag-instituto-americas","tag-perspectivas-de-los-yankees","tag-texas-tech","tag-valor-de-la-ranura","tag-yankees-de-nueva-york"],"acf":[],"_links":{"self":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/241908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/comments?post=241908"}],"version-history":[{"count":1,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/241908\/revisions"}],"predecessor-version":[{"id":241909,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/posts\/241908\/revisions\/241909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media\/241906"}],"wp:attachment":[{"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/media?parent=241908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/categories?post=241908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pinstripesnation.com\/es\/wp-json\/wp\/v2\/tags?post=241908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}